{"id":101854,"date":"2024-04-21T13:01:37","date_gmt":"2024-04-21T12:01:37","guid":{"rendered":"http:\/\/diadem.com\/the7_project\/diasafe-single\/"},"modified":"2025-08-05T11:56:14","modified_gmt":"2025-08-05T10:56:14","slug":"diasafe-single","status":"publish","type":"the7_project","link":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/","title":{"rendered":"DiaSafe\u00ae Single"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"101854\" class=\"elementor elementor-101854 elementor-98041\" data-elementor-post-type=\"the7_project\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ef61fc7 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"5ef61fc7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-283425f7\" data-id=\"283425f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-601c688c elementor-widget elementor-widget-heading\" data-id=\"601c688c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Produkt<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cae761d elementor-widget elementor-widget-image\" data-id=\"cae761d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"541\" height=\"510\" src=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasafe-single-pis-retegrend-en.png\" class=\"attachment-large size-large wp-image-100903\" alt=\"Gr\u00fcndach-Schichtaufbau im Schnitt mit dem DiaSafe Single Absturzsicherungssystem, Kies-Substrat, Dr\u00e4nschicht und wurzelfeste Abdichtung.\" srcset=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasafe-single-pis-retegrend-en.png 541w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasafe-single-pis-retegrend-en-300x283.png 300w\" sizes=\"(max-width: 541px) 100vw, 541px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec5c5f7 elementor-widget elementor-widget-image\" data-id=\"ec5c5f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"596\" height=\"415\" src=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasafe-emblema-en.png\" class=\"attachment-large size-large wp-image-100905\" alt=\"\" srcset=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasafe-emblema-en.png 596w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasafe-emblema-en-300x209.png 300w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38f3e438\" data-id=\"38f3e438\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71558093 elementor-widget elementor-widget-heading\" data-id=\"71558093\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informationsblatt herunterladen <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17917677 elementor-widget elementor-widget-text-editor\" data-id=\"17917677\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/diadem.com\/wp-content\/uploads\/2025\/05\/DiaSafe_Single_PIB_09014804_DE.pdf\">Produktinformationsblatt<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1af0e0 elementor-widget elementor-widget-heading\" data-id=\"e1af0e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produktbeschreibung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0193e84 elementor-widget elementor-widget-text-editor\" data-id=\"0193e84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durch Schichtaufbau (z.B.: Gr\u00fcndach; Kies) fixierte Anschlageinrichtung als Auffang- und R\u00fcckhaltesystem ohne Durchdringung der Dachhaut f\u00fcr gleichzeitige Benutzung durch 1+1 Benutzer, bei einem Benutzer als R\u00fcckhaltesystem bei dem anderen Benutzer als Auffangsystem, nach EN 795:2012 Klasse A und CEN\/TS 16415:2013 zertifiziert, f\u00fcr Flachd\u00e4cher bis 5\u00b0 Dachneigung, inkl. aller Bestandteile aus nicht rostendem Stahl, resistent gegen Sauerregen in Industriegebieten und salzhaltige Luft in K\u00fcstenregionen, mit DS-Am\u00f6be- Fangschlitten mit integriertem Absturzsicherungsteppich (3 x 3 m) in Signalfarbe gr\u00fcn, und mit GFK-Kegel mit Markierungslinien f\u00fcr Mindest-Sch\u00fctth\u00f6he, geliefert inkl. allem Zubeh\u00f6r fach- und abnahmegerecht im Sinn und gem\u00e4\u00df der Herstellervorgaben, den Flachdachrichtlinien und des Verlegeplanes mit vollfl\u00e4chig verteiltem Auflastmaterial von min. 80 kg\/m2 eingebaut.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5622f3f1 elementor-widget elementor-widget-heading\" data-id=\"5622f3f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vorteile<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bbc24fe elementor-widget elementor-widget-text-editor\" data-id=\"2bbc24fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Vermeidung von W\u00e4rmebr\u00fccken \u21d2 Befestigungselemente sind f\u00fcr Einbau nicht n\u00f6tig<\/li><li>Durch Schichtaufbau (z.B.: Gr\u00fcndach; Kies) gesichert \u21d2 ohne Durchdringung der Dachabdichtung befestigbar<\/li><li>Korrosionsbest\u00e4ndig \u21d2 auch in K\u00fcstenregionen und Industriegebieten mit sauerem Regen verwendbar<\/li><li>Schutz f\u00fcr mehrere Personen \u21d2 je nach Auflastgewicht f\u00fcr 1+1 arbeitende Personen<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-357b7d3 elementor-widget elementor-widget-image\" data-id=\"357b7d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"737\" src=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-Single-1-1024x737.png\" class=\"attachment-large size-large wp-image-103925\" alt=\"Gr\u00fcndach-Schichtaufbau im Schnitt mit dem DiaSafe Single Absturzsicherungssystem, Kies-Substrat, Dr\u00e4nschicht und wurzelfeste Abdichtung.\" srcset=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-Single-1-1024x737.png 1024w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-Single-1-300x216.png 300w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-Single-1-768x553.png 768w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-Single-1.png 1312w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bc7bd7 elementor-widget elementor-widget-image\" data-id=\"1bc7bd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"727\" src=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-SIngle-2-1024x727.png\" class=\"attachment-large size-large wp-image-103928\" alt=\"Gr\u00fcndach-Schichtaufbau im Schnitt mit dem DiaSafe Single Absturzsicherungssystem, Kies-Substrat, Dr\u00e4nschicht und wurzelfeste Abdichtung.\" srcset=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-SIngle-2-1024x727.png 1024w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-SIngle-2-300x213.png 300w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-SIngle-2-768x545.png 768w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/DS-SIngle-2.png 1113w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a716c53 elementor-widget elementor-widget-heading\" data-id=\"a716c53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DIADEM\u00ae Schichtaufbau, Schnelle und einfache Installation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9430aa elementor-widget elementor-widget-image\" data-id=\"b9430aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasingle-schichtaufbau-1024x446.png\" class=\"attachment-large size-large wp-image-110887\" alt=\"Gr\u00fcndach-Schichtaufbau im Schnitt mit dem DiaSafe Single Absturzsicherungssystem, Kies-Substrat, Dr\u00e4nschicht und wurzelfeste Abdichtung.\" srcset=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasingle-schichtaufbau-1024x446.png 1024w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasingle-schichtaufbau-300x131.png 300w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasingle-schichtaufbau-768x334.png 768w, https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/diasingle-schichtaufbau.png 1310w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a681264 elementor-widget elementor-widget-heading\" data-id=\"2a681264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anwendung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262649a elementor-widget elementor-widget-text-editor\" data-id=\"262649a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_row wpb_row row top-row\"><div class=\"vc_column_container col-md-4\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"wpb_text_column wpb_content_element \"><div class=\"wpb_wrapper\"><p>Zur Sicherung von Personen, die auf Flachd\u00e4chern mit bis zu 5\u00b0 Neigung arbeiten. Das System kann sowohl als Auffang- als auch als R\u00fcckhaltesystem verwendet werden.<\/p><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1761549f elementor-widget elementor-widget-heading\" data-id=\"1761549f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technische daten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92a130a elementor-widget elementor-widget-text-editor\" data-id=\"92a130a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td><strong>Bez\u00fcgliche Normen:<\/strong> EN795:2012; CEN\/TS 16415:2012; D.A.CH.S Richtlinien; \u00d6NORM B3417<\/td><\/tr><tr><td><strong>Integrierter Sicherungsteppich f\u00fcr Auflast (m):<\/strong> 3\u00d73**<\/td><\/tr><tr><td><strong>**Gewicht der Auflast: <\/strong> 80 kg\/m<sup>2<\/sup><\/td><\/tr><tr><td><strong>Maximale Zugspannung in der Dachhaut gem\u00e4\u00df Sachverst\u00e4ndigen \u2013 Gutachten:<\/strong> 0,00155 N\/mm<sup>2<\/sup><\/td><\/tr><tr><td><strong>Anwendung von mehreren Personen:<\/strong> ja<\/td><\/tr><tr><td><strong>In der N\u00e4he vom Seeufer und auf dem Industriegebiet verwendbar:<\/strong> ja<\/td><\/tr><tr><td><strong>In der Winterzeit (Eis, Schnee) benutzbar:<\/strong> ja<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anschlageinrichtung System (Artikelnummer: 130097)<\/p>\n","protected":false},"featured_media":100913,"template":"","meta":{"_acf_changed":false},"the7_project_category":[388],"class_list":["post-101854","the7_project","type-the7_project","status-publish","has-post-thumbnail","hentry","the7_project_category-durch-schichtaufbau-gesicherte-systeme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>DiaSafe\u00ae Single - Diadem<\/title>\n<meta name=\"description\" content=\"Der DiaSafe\u00ae Single ist ein einzelner Anschlagpunkt f\u00fcr die Absturzsicherung auf Flachd\u00e4chern,mit dem Dachaufbau ballastiert \u2013 ohne W\u00e4rmebr\u00fccken und ohne Dachdurchdringung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DiaSafe\u00ae Single\" \/>\n<meta property=\"og:description\" content=\"Der DiaSafe\u00ae Single ist ein einzelner Anschlagpunkt f\u00fcr die Absturzsicherung auf Flachd\u00e4chern,mit dem Dachaufbau ballastiert \u2013 ohne W\u00e4rmebr\u00fccken und ohne Dachdurchdringung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/\" \/>\n<meta property=\"og:site_name\" content=\"Diadem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diadem.greenroof\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T10:56:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/kep3-1-300x300-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/\",\"url\":\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/\",\"name\":\"DiaSafe\u00ae Single - Diadem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diadem.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/kep3-1-300x300-1.jpg\",\"datePublished\":\"2024-04-21T12:01:37+00:00\",\"dateModified\":\"2025-08-05T10:56:14+00:00\",\"description\":\"Der DiaSafe\u00ae Single ist ein einzelner Anschlagpunkt f\u00fcr die Absturzsicherung auf Flachd\u00e4chern,mit dem Dachaufbau ballastiert \u2013 ohne W\u00e4rmebr\u00fccken und ohne Dachdurchdringung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diadem.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/kep3-1-300x300-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diadem.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/kep3-1-300x300-1.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/the7_project\\\/diasafe-single\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/diadem.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DiaSafe\u00ae Single\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/diadem.com\\\/de\\\/\",\"name\":\"Diadem\",\"description\":\"Green Up The Roof!\",\"publisher\":{\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diadem.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/#organization\",\"name\":\"Diadem\",\"url\":\"https:\\\/\\\/diadem.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diadem.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2.png\",\"contentUrl\":\"https:\\\/\\\/diadem.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2.png\",\"width\":1920,\"height\":1080,\"caption\":\"Diadem\"},\"image\":{\"@id\":\"https:\\\/\\\/diadem.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diadem.greenroof\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DiaSafe\u00ae Single - Diadem","description":"Der DiaSafe\u00ae Single ist ein einzelner Anschlagpunkt f\u00fcr die Absturzsicherung auf Flachd\u00e4chern,mit dem Dachaufbau ballastiert \u2013 ohne W\u00e4rmebr\u00fccken und ohne Dachdurchdringung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/","og_locale":"de_DE","og_type":"article","og_title":"DiaSafe\u00ae Single","og_description":"Der DiaSafe\u00ae Single ist ein einzelner Anschlagpunkt f\u00fcr die Absturzsicherung auf Flachd\u00e4chern,mit dem Dachaufbau ballastiert \u2013 ohne W\u00e4rmebr\u00fccken und ohne Dachdurchdringung.","og_url":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/","og_site_name":"Diadem","article_publisher":"https:\/\/www.facebook.com\/diadem.greenroof","article_modified_time":"2025-08-05T10:56:14+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/kep3-1-300x300-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/","url":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/","name":"DiaSafe\u00ae Single - Diadem","isPartOf":{"@id":"https:\/\/diadem.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/#primaryimage"},"image":{"@id":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/#primaryimage"},"thumbnailUrl":"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/kep3-1-300x300-1.jpg","datePublished":"2024-04-21T12:01:37+00:00","dateModified":"2025-08-05T10:56:14+00:00","description":"Der DiaSafe\u00ae Single ist ein einzelner Anschlagpunkt f\u00fcr die Absturzsicherung auf Flachd\u00e4chern,mit dem Dachaufbau ballastiert \u2013 ohne W\u00e4rmebr\u00fccken und ohne Dachdurchdringung.","breadcrumb":{"@id":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/#primaryimage","url":"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/kep3-1-300x300-1.jpg","contentUrl":"https:\/\/diadem.com\/wp-content\/uploads\/2024\/04\/kep3-1-300x300-1.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/diadem.com\/de\/the7_project\/diasafe-single\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diadem.com\/de\/"},{"@type":"ListItem","position":2,"name":"DiaSafe\u00ae Single"}]},{"@type":"WebSite","@id":"https:\/\/diadem.com\/de\/#website","url":"https:\/\/diadem.com\/de\/","name":"Diadem","description":"Green Up The Roof!","publisher":{"@id":"https:\/\/diadem.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diadem.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/diadem.com\/de\/#organization","name":"Diadem","url":"https:\/\/diadem.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diadem.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/diadem.com\/wp-content\/uploads\/2020\/11\/2.png","contentUrl":"https:\/\/diadem.com\/wp-content\/uploads\/2020\/11\/2.png","width":1920,"height":1080,"caption":"Diadem"},"image":{"@id":"https:\/\/diadem.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diadem.greenroof"]}]}},"_links":{"self":[{"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/the7_project\/101854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/the7_project"}],"about":[{"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/types\/the7_project"}],"version-history":[{"count":29,"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/the7_project\/101854\/revisions"}],"predecessor-version":[{"id":114798,"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/the7_project\/101854\/revisions\/114798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/media\/100913"}],"wp:attachment":[{"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/media?parent=101854"}],"wp:term":[{"taxonomy":"the7_project_category","embeddable":true,"href":"https:\/\/diadem.com\/de\/wp-json\/wp\/v2\/the7_project_category?post=101854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}